{"id":611,"date":"2026-07-14T18:02:18","date_gmt":"2026-07-14T15:02:18","guid":{"rendered":"https:\/\/www.remind-by-quran.com\/?post_type=media_lib&#038;p=611"},"modified":"2026-07-14T18:02:19","modified_gmt":"2026-07-14T15:02:19","slug":"das-zeugnis-von-jesus-isa-und-das-schicksal-der-diener","status":"publish","type":"media_lib","link":"https:\/\/www.remind-by-quran.com\/de\/media_lib\/der-messias-friede-sei-mit-ihm-im-heiligen-koran\/das-zeugnis-von-jesus-isa-und-das-schicksal-der-diener\/","title":{"rendered":"Das Zeugnis von Jesus (Isa) und das Schicksal der Diener"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Diese Verse beginnen mit der Versammlung der Gesandten am J\u00fcngsten Tag und erinnern an Allahs Gaben f\u00fcr Jesus und seine gewaltigen Wunder. Allah erinnert Jesus an das Sprechen in der Wiege, das Heilen von Blinden, das Totenauferwecken und das Formen von V\u00f6geln aus Ton. Der Text beschreibt die J\u00fcnger, die einen vom Himmel herabgesandten Tisch zur Beruhigung ihrer Herzen erbaten, den Allah unter Warnung gew\u00e4hrte. Es folgt die gro\u00dfe Befragung, ob Jesus den Menschen befohlen habe, ihn und seine Mutter als G\u00f6tter zu nehmen, was er ehrf\u00fcrchtig ablehnt. Jesus betont, er habe ihnen nur befohlen, Allah zu dienen, seinem und ihrem Herrn, und stellt ihre Bestrafung oder Vergebung in Allahs Hand. Die Sure schlie\u00dft mit dem Triumph der Wahrhaftigen im Paradies und der Erkl\u00e4rung, dass Allah die absolute Herrschaft \u00fcber Himmel und Erde besitzt.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Diese Verse beginnen mit der Versammlung der Gesandten am J\u00fcngsten Tag und erinnern an Allahs Gab&#8230;<\/p>\n","protected":false},"featured_media":569,"parent":568,"menu_order":0,"template":"","meta":{"_acf_changed":true},"media_sectors":[3],"class_list":["post-611","media_lib","type-media_lib","status-publish","has-post-thumbnail","hentry","media_sectors-jesus-in-quraan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media_lib\/611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media_lib"}],"about":[{"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/types\/media_lib"}],"up":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media_lib\/568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media\/569"}],"wp:attachment":[{"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media?parent=611"}],"wp:term":[{"taxonomy":"media_sectors","embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media_sectors?post=611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}