{"id":615,"date":"2026-07-14T18:11:14","date_gmt":"2026-07-14T15:11:14","guid":{"rendered":"https:\/\/www.remind-by-quran.com\/?post_type=media_lib&#038;p=615"},"modified":"2026-07-14T18:11:14","modified_gmt":"2026-07-14T15:11:14","slug":"el-milagro-del-nacimiento-de-jesus-y-su-verdad","status":"publish","type":"media_lib","link":"https:\/\/www.remind-by-quran.com\/de\/media_lib\/el-mesias-la-paz-sea-con-el-en-el-santo-coran\/el-milagro-del-nacimiento-de-jesus-y-su-verdad\/","title":{"rendered":"El milagro del nacimiento de Jes\u00fas y su verdad"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Estos vers\u00edculos comienzan con el retiro de Mar\u00eda, a quien Al\u00e1 envi\u00f3 al \u00e1ngel Gabriel en forma humana para anunciarle un hijo puro. Narran el parto de Mar\u00eda bajo una palmera que le provey\u00f3 d\u00e1tiles frescos, y el consuelo de Al\u00e1 con un arroyo a sus pies. Mar\u00eda se present\u00f3 ante su pueblo llevando al beb\u00e9, y ante sus acusaciones, lo se\u00f1al\u00f3 para que hablara a pesar de ser un reci\u00e9n nacido. Jes\u00fas habl\u00f3 en la cuna para defender a su madre, declarando ser un siervo de Al\u00e1, quien le dio el Libro y lo hizo profeta bendito. Los vers\u00edculos afirman que Jes\u00fas es la palabra de verdad sobre la cual dudan, rechazando totalmente que Al\u00e1 adopte un hijo. Concluyen con una advertencia sobre el D\u00eda del Lamento, cuando se decida el destino final mientras los hombres siguen indiferentes.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Estos vers\u00edculos comienzan con el retiro de Mar\u00eda, a quien Al\u00e1 envi\u00f3 al \u00e1ngel Gabriel en forma hu&#8230;<\/p>\n","protected":false},"featured_media":571,"parent":570,"menu_order":0,"template":"","meta":{"_acf_changed":true},"media_sectors":[3],"class_list":["post-615","media_lib","type-media_lib","status-publish","has-post-thumbnail","hentry","media_sectors-jesus-in-quraan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media_lib\/615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media_lib"}],"about":[{"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/types\/media_lib"}],"up":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media_lib\/570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media\/571"}],"wp:attachment":[{"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media?parent=615"}],"wp:term":[{"taxonomy":"media_sectors","embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/de\/wp-json\/wp\/v2\/media_sectors?post=615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}