{"id":549,"date":"2026-07-14T11:35:04","date_gmt":"2026-07-14T08:35:04","guid":{"rendered":"https:\/\/www.remind-by-quran.com\/?post_type=media_lib&#038;p=549"},"modified":"2026-07-14T11:35:06","modified_gmt":"2026-07-14T08:35:06","slug":"549-2","status":"publish","type":"media_lib","link":"https:\/\/www.remind-by-quran.com\/en\/media_lib\/%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b9%80%e0%b8%a3%e0%b8%b4%e0%b9%88%e0%b8%a1%e0%b8%95%e0%b9%89%e0%b8%99%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87\/549-2\/","title":{"rendered":""},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>\u0e04\u0e27\u0e32\u0e21\u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e14\u0e38\u0e25\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e31\u0e01\u0e23\u0e27\u0e32\u0e25<\/strong><\/li>\n<\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u0e42\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e08\u0e32\u0e01\u0e2a\u0e39\u0e40\u0e23\u0e32\u0e30\u0e2e\u0e4c \u0e2d\u0e31\u0e23-\u0e40\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e21\u0e32\u0e19 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e0a\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e42\u0e1b\u0e23\u0e14\u0e1b\u0e23\u0e32\u0e19\u0e2d\u0e31\u0e19\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e2d\u0e31\u0e25\u0e01\u0e38\u0e23\u0e2d\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e27\u0e32\u0e17\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e44\u0e14\u0e49\u0e40\u0e1c\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e2b\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e43\u0e19\u0e08\u0e31\u0e01\u0e23\u0e27\u0e32\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e42\u0e04\u0e08\u0e23\u0e02\u0e2d\u0e07\u0e14\u0e27\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e14\u0e27\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e22\u0e2d\u0e21\u0e2a\u0e22\u0e1a\u0e02\u0e2d\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e1e\u0e23\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e17\u0e23\u0e07\u0e40\u0e19\u0e49\u0e19\u0e22\u0e49\u0e33\u0e16\u0e36\u0e07\u0e15\u0e23\u0e32\u0e0a\u0e39\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e38\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e17\u0e23\u0e07\u0e27\u0e32\u0e07\u0e44\u0e27\u0e49\u0e1a\u0e19\u0e1c\u0e37\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e39\u0e01\u0e15\u0e23\u0e30\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e44\u0e27\u0e49\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e42\u0e1b\u0e23\u0e14\u0e1b\u0e23\u0e32\u0e19\u0e2d\u0e31\u0e19\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e01\u0e34\u0e19\u0e04\u0e13\u0e19\u0e32 \u0e42\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e22\u0e31\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e16\u0e36\u0e07\u0e15\u0e49\u0e19\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e08\u0e32\u0e01\u0e14\u0e34\u0e19\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e41\u0e2b\u0e49\u0e07\u0e14\u0e31\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e31\u0e49\u0e19\u0e14\u0e34\u0e19\u0e40\u0e1c\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0d\u0e34\u0e19\u0e08\u0e32\u0e01\u0e40\u0e1b\u0e25\u0e27\u0e44\u0e1f \u0e0b\u0e36\u0e48\u0e07\u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e16\u0e36\u0e07\u0e40\u0e14\u0e0a\u0e32\u0e19\u0e38\u0e20\u0e32\u0e1e\u0e2d\u0e31\u0e19\u0e44\u0e23\u0e49\u0e02\u0e35\u0e14\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e19\u0e33\u0e40\u0e23\u0e32\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e25\u0e35\u0e49\u0e25\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e17\u0e49\u0e2d\u0e07\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e1a\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e30\u0e40\u0e25\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e21\u0e35\u0e17\u0e35\u0e48\u0e04\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e2d\u0e43\u0e1a\u0e2d\u0e31\u0e19\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e25\u0e2d\u0e22\u0e25\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e38\u0e08\u0e02\u0e38\u0e19\u0e40\u0e02\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e34\u0e14\u0e17\u0e49\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e23\u0e34\u0e07\u0e2d\u0e31\u0e19\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e0d\u0e02\u0e2d\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e31\u0e49\u0e07\u0e21\u0e27\u0e25\u0e1a\u0e19\u0e42\u0e25\u0e01\u0e43\u0e1a\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e04\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e23\u0e30\u0e1e\u0e31\u0e01\u0e15\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e1c\u0e39\u0e49\u0e2d\u0e20\u0e34\u0e1a\u0e32\u0e25\u0e1c\u0e39\u0e49\u0e17\u0e23\u0e07\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e28\u0e41\u0e25\u0e30\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>\u0e42\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e08\u0e32\u0e01\u0e2a\u0e39\u0e40\u0e23\u0e32\u0e30\u0e2e\u0e4c \u0e2d\u0e31\u0e23-\u0e40\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e21\u0e32\u0e19 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e0a\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e42\u0e1b\u0e23\u0e14\u0e1b\u0e23\u0e32\u0e19\u0e2d\u0e31\u0e19\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e19\u0e31\u0e48\u0e19\u0e04&#8230;<\/p>\n","protected":false},"featured_media":400,"parent":303,"menu_order":0,"template":"","meta":{"_acf_changed":true},"media_sectors":[2],"class_list":["post-549","media_lib","type-media_lib","status-publish","has-post-thumbnail","hentry","media_sectors-starting-story"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.remind-by-quran.com\/en\/wp-json\/wp\/v2\/media_lib\/549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.remind-by-quran.com\/en\/wp-json\/wp\/v2\/media_lib"}],"about":[{"href":"https:\/\/www.remind-by-quran.com\/en\/wp-json\/wp\/v2\/types\/media_lib"}],"up":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/en\/wp-json\/wp\/v2\/media_lib\/303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/en\/wp-json\/wp\/v2\/media\/400"}],"wp:attachment":[{"href":"https:\/\/www.remind-by-quran.com\/en\/wp-json\/wp\/v2\/media?parent=549"}],"wp:term":[{"taxonomy":"media_sectors","embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/en\/wp-json\/wp\/v2\/media_sectors?post=549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}