{"id":594,"date":"2026-07-14T16:08:30","date_gmt":"2026-07-14T13:08:30","guid":{"rendered":"https:\/\/www.remind-by-quran.com\/?post_type=media_lib&#038;p=594"},"modified":"2026-07-14T16:08:31","modified_gmt":"2026-07-14T13:08:31","slug":"la-verdad-sobre-jesus-isa-y-el-debate-por-la-realidad","status":"publish","type":"media_lib","link":"https:\/\/www.remind-by-quran.com\/es\/media_lib\/el-mesias-la-paz-sea-con-el-en-el-santo-coran\/la-verdad-sobre-jesus-isa-y-el-debate-por-la-realidad\/","title":{"rendered":"La verdad sobre Jes\u00fas (Isa) y el debate por la realidad"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Estos vers\u00edculos comienzan con la anunciaci\u00f3n de los \u00e1ngeles a Mar\u00eda sobre el Verbo de Al\u00e1: el Mes\u00edas, Jes\u00fas, honrado en este mundo y el pr\u00f3ximo. Detallan sus milagros por permiso de Al\u00e1: hablar en la cuna, crear aves de barro, curar enfermos y resucitar muertos. Los vers\u00edculos confirman que Jes\u00fas es un siervo de Al\u00e1, creado de polvo como Ad\u00e1n, refutando falsas atribuciones de divinidad. El discurso pasa al debate con los cristianos de Nayr\u00e1n, aclarando que la creaci\u00f3n de Jes\u00fas es similar a la de Ad\u00e1n. Al\u00e1 ordena al profeta Mahoma invocar la Mubahala contra aquellos que discuten falsamente despu\u00e9s de haber recibido la verdad clara. Concluyen afirmando que esta es la verdad absoluta, enfatizando el poder y la sabidur\u00eda de Al\u00e1 y advirtiendo contra el desv\u00edo.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Estos vers\u00edculos comienzan con la anunciaci\u00f3n de los \u00e1ngeles a Mar\u00eda sobre el Verbo de Al\u00e1: el Me&#8230;<\/p>\n","protected":false},"featured_media":571,"parent":570,"menu_order":0,"template":"","meta":{"_acf_changed":true},"media_sectors":[3],"class_list":["post-594","media_lib","type-media_lib","status-publish","has-post-thumbnail","hentry","media_sectors-jesus-in-quraan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.remind-by-quran.com\/es\/wp-json\/wp\/v2\/media_lib\/594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.remind-by-quran.com\/es\/wp-json\/wp\/v2\/media_lib"}],"about":[{"href":"https:\/\/www.remind-by-quran.com\/es\/wp-json\/wp\/v2\/types\/media_lib"}],"up":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/es\/wp-json\/wp\/v2\/media_lib\/570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/es\/wp-json\/wp\/v2\/media\/571"}],"wp:attachment":[{"href":"https:\/\/www.remind-by-quran.com\/es\/wp-json\/wp\/v2\/media?parent=594"}],"wp:term":[{"taxonomy":"media_sectors","embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/es\/wp-json\/wp\/v2\/media_sectors?post=594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}