{"id":586,"date":"2026-07-14T15:11:48","date_gmt":"2026-07-14T12:11:48","guid":{"rendered":"https:\/\/www.remind-by-quran.com\/?post_type=media_lib&#038;p=586"},"modified":"2026-07-14T15:11:49","modified_gmt":"2026-07-14T12:11:49","slug":"la-eleccion-divina-y-la-historia-de-la-familia-de-imran","status":"publish","type":"media_lib","link":"https:\/\/www.remind-by-quran.com\/pt-pt\/media_lib\/el-mesias-la-paz-sea-con-el-en-el-santo-coran\/la-eleccion-divina-y-la-historia-de-la-familia-de-imran\/","title":{"rendered":"La Elecci\u00f3n Divina y la Historia de la Familia de Imr\u00e1n"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Estos vers\u00edculos comienzan declarando la pura elecci\u00f3n de Al\u00e1 de Ad\u00e1n, No\u00e9, la familia de Abraham y la familia de Imr\u00e1n sobre la humanidad. Narran la historia de la esposa de Imr\u00e1n, quien consagr\u00f3 su hijo no nacido al servicio de Al\u00e1, dando a luz a Mar\u00eda. El profeta Zacar\u00edas asumi\u00f3 la tutela de Mar\u00eda y, cada vez que entraba en su santuario, encontraba alimentos provistos milagrosamente por Al\u00e1. Inspirado por esto, Zacar\u00edas rog\u00f3 por un hijo piadoso a pesar de su vejez, y los \u00e1ngeles le anunciaron la buena nueva de Juan. Los vers\u00edculos destacan la pureza de Mar\u00eda y su elecci\u00f3n por encima de todas las mujeres del mundo, inst\u00e1ndola a la adoraci\u00f3n devota. Concluyen se\u00f1alando que estas historias son parte de la revelaci\u00f3n de lo oculto enviada al profeta Mahoma, quien no estuvo presente all\u00ed.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Estos vers\u00edculos comienzan declarando la pura elecci\u00f3n de Al\u00e1 de Ad\u00e1n, No\u00e9, la familia de Abraham&#8230;<\/p>\n","protected":false},"featured_media":571,"parent":570,"menu_order":0,"template":"","meta":{"_acf_changed":true},"media_sectors":[3],"class_list":["post-586","media_lib","type-media_lib","status-publish","has-post-thumbnail","hentry","media_sectors-jesus-in-quraan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.remind-by-quran.com\/pt-pt\/wp-json\/wp\/v2\/media_lib\/586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.remind-by-quran.com\/pt-pt\/wp-json\/wp\/v2\/media_lib"}],"about":[{"href":"https:\/\/www.remind-by-quran.com\/pt-pt\/wp-json\/wp\/v2\/types\/media_lib"}],"up":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/pt-pt\/wp-json\/wp\/v2\/media_lib\/570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/pt-pt\/wp-json\/wp\/v2\/media\/571"}],"wp:attachment":[{"href":"https:\/\/www.remind-by-quran.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=586"}],"wp:term":[{"taxonomy":"media_sectors","embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/pt-pt\/wp-json\/wp\/v2\/media_sectors?post=586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}