{"id":603,"date":"2026-07-14T16:29:50","date_gmt":"2026-07-14T13:29:50","guid":{"rendered":"https:\/\/www.remind-by-quran.com\/?post_type=media_lib&#038;p=603"},"modified":"2026-07-14T16:29:51","modified_gmt":"2026-07-14T13:29:51","slug":"o-testemunho-de-jesus-isa-e-o-destino-dos-servos","status":"publish","type":"media_lib","link":"https:\/\/www.remind-by-quran.com\/th\/media_lib\/o-messias-que-a-paz-esteja-com-ele-no-alcorao-sagrado\/o-testemunho-de-jesus-isa-e-o-destino-dos-servos\/","title":{"rendered":"O Testemunho de Jesus (Isa) e o Destino dos Servos"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Estes vers\u00edculos come\u00e7am com a reuni\u00e3o dos mensageiros no Dia do Ju\u00edzo, lembrando os favores de Deus para com Jesus e os seus milagres. Deus lembra a Jesus o falar no ber\u00e7o, o curar os cegos, o ressuscitar os mortos e o moldar aves de barro com a Sua permiss\u00e3o. O texto revisita a hist\u00f3ria dos disc\u00edpulos que pediram uma mesa servida do c\u00e9u para confortar os seus cora\u00e7\u00f5es, concedida sob severo aviso. Segue-se o grande interrogat\u00f3rio onde Deus pergunta a Jesus se ele disse \u00e0s pessoas para ador\u00e1-lo e \u00e0 sua m\u00e3e, o que ele nega com respeito. Jesus afirma que apenas lhes ordenou adorar a Deus, seu Senhor e deles, deixando a puni\u00e7\u00e3o ou o perd\u00e3o dos homens nas m\u00e3os de Deus. A surata conclui elogiando os verazes que ganham o Para\u00edso, declarando que a Deus pertence o dom\u00ednio absoluto dos c\u00e9us e da terra.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Estes vers\u00edculos come\u00e7am com a reuni\u00e3o dos mensageiros  [&hellip;]<\/p>\n","protected":false},"featured_media":573,"parent":572,"menu_order":0,"template":"","meta":{"_acf_changed":true},"media_sectors":[3],"class_list":["post-603","media_lib","type-media_lib","status-publish","has-post-thumbnail","hentry","media_sectors-jesus-in-quraan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.remind-by-quran.com\/th\/wp-json\/wp\/v2\/media_lib\/603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.remind-by-quran.com\/th\/wp-json\/wp\/v2\/media_lib"}],"about":[{"href":"https:\/\/www.remind-by-quran.com\/th\/wp-json\/wp\/v2\/types\/media_lib"}],"up":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/th\/wp-json\/wp\/v2\/media_lib\/572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/th\/wp-json\/wp\/v2\/media\/573"}],"wp:attachment":[{"href":"https:\/\/www.remind-by-quran.com\/th\/wp-json\/wp\/v2\/media?parent=603"}],"wp:term":[{"taxonomy":"media_sectors","embeddable":true,"href":"https:\/\/www.remind-by-quran.com\/th\/wp-json\/wp\/v2\/media_sectors?post=603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}